{"id":19,"date":"2016-05-23T10:34:52","date_gmt":"2016-05-23T08:34:52","guid":{"rendered":"http:\/\/localhost\/margaritelli\/?page_id=19"},"modified":"2026-06-01T08:06:30","modified_gmt":"2026-06-01T06:06:30","slug":"company","status":"publish","type":"page","link":"https:\/\/margaritelli-rs.com\/it\/company\/","title":{"rendered":"Company"},"content":{"rendered":"<div id=\"pl-19\"  class=\"panel-layout\" ><div id=\"pg-19-0\"  class=\"panel-grid panel-has-style\" ><div class=\"ik pageSection panel-row-style panel-row-style-for-19-0\" ><div id=\"pgc-19-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-0-0-0\" class=\"so-panel widget widget_qzr-maincontent panel-first-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-19-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\t\t\t<h2 style=\"color:#7b898e\">Margaritelli Ferroviaria SpA<\/h2>\n\t\t\n\t\t\t\t\t<div class=\"decoration\" style=\"background-color: #7b898e\"><\/div>\n\t\t\n\t\t\t\t\t<h3 class=\"maincontent-subtitle\" style=\"color:\">OLTRE 150 ANNI DI PASSIONE PER L'INNOVAZIONE<\/h3>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center dontShowOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: center;\">Fin dalle origini, Margaritelli ha legato il proprio nome al legno e alle ferrovie, contribuendo alla ricostruzione del Paese nel secondo dopoguerra e all'apertura di\u00a0nuove vie di comunicazione. La ferrovia che sempre simboleggia progresso e civilt\u00e0 e rappresenta la modalit\u00e0 di trasporto pi\u00f9 sicura e sostenibile. Motivati da grande passione per la tecnica e la qualit\u00e0 dei prodotti, operiamo per dare un contributo allo sviluppo del trasporto ferroviario in Italia e nel mondo. Reattivit\u00e0, dinamismo e processi snelli consentono a Margaritelli Ferroviaria di\u00a0muoversi al ritmo dell'innovazione tecnologica, sviluppando nuove\u00a0soluzioni adatte alle esigenze del settore.<\/p>\n<p><img class=\"alignnone size-medium wp-image-771 aligncenter\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/10\/margaritelli_ferroviaria_logo_512x512-300x300.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: center;\">Fin dalle origini, Margaritelli ha legato il proprio nome al legno e alle ferrovie, contribuendo alla ricostruzione del Paese nel secondo dopoguerra e all'apertura di\u00a0nuove vie di comunicazione. La ferrovia che sempre simboleggia progresso e civilt\u00e0 e rappresenta la modalit\u00e0 di trasporto pi\u00f9 sicura e sostenibile. Motivati da grande passione per la tecnica e la qualit\u00e0 dei prodotti, operiamo per dare un contributo allo sviluppo del trasporto ferroviario in Italia e nel mondo. Reattivit\u00e0, dinamismo e processi snelli consentono a Margaritelli Ferroviaria di\u00a0muoversi al ritmo dell'innovazione tecnologica, sviluppando nuove\u00a0soluzioni adatte alle esigenze del settore.<\/p>\n<p><img class=\"alignnone size-medium wp-image-771 aligncenter\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/10\/margaritelli_ferroviaria_logo_512x512-300x300.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><div id=\"panel-19-0-0-1\" class=\"so-panel widget widget_qzr-sectionbutton panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-sectionbutton so-widget-qzr-sectionbutton-base\"\n\t\t\t\n\t\t><div class=\"sectionbutton-wrapper-large columns-10 center colPadding\">\n\t\t\t\t\t<div class=\"colPadding sectionbutton-item-large\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/www.margaritelliferroviaria.com\/it\/\">Visita il sito per maggiori informazioni<\/a><\/h3>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.margaritelliferroviaria.com\/it\/\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-1\"  class=\"panel-grid panel-has-style\" ><div class=\"ik siteorigin-panels-stretch panel-row-style panel-row-style-for-19-1\" data-stretch-type=\"full\" ><div id=\"pgc-19-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-1-0-0\" class=\"so-panel widget widget_qzr-maincontent panel-first-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-19-1-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\t\t\t<h2 style=\"color:#7b898e\">Margaritelli Road Safety<\/h2>\n\t\t\n\t\t\t\t\t<div class=\"decoration\" style=\"background-color: #7b898e\"><\/div>\n\t\t\n\t\t\t\t\t<h3 class=\"maincontent-subtitle\" style=\"color:\">Margaritelli Road Safety \u00e8 un brand di Margaritelli Ferroviaria SpA<\/h3>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center dontShowOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: center;\">Dall'esperienza centenaria nella lavorazione del legno della famiglia Margaritelli, nascono i prodotti Margaritelli Road Safety.<br \/>\nLinee essenziali e design raffinato, assoluta qualit\u00e0 costruttiva, accurata selezione delle materie prime, avanzate tecnologie<br \/>\ndi lavorazione: sono questi gli elementi che contraddistinguono il brand.<\/p>\n<p><img class=\"size-medium wp-image-5373 aligncenter\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2022\/06\/logo-300x300.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<\/div>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: center;\">Dall'esperienza centenaria nella lavorazione del legno della famiglia Margaritelli, nascono i prodotti Margaritelli Road Safety.<br \/>\nLinee essenziali e design raffinato, assoluta qualit\u00e0 costruttiva, accurata selezione delle materie prime, avanzate tecnologie<br \/>\ndi lavorazione: sono questi gli elementi che contraddistinguono il brand.<\/p>\n<p><img class=\"size-medium wp-image-5373 aligncenter\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2022\/06\/logo-300x300.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><div id=\"panel-19-1-0-1\" class=\"so-panel widget widget_qzr-sectionbutton\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-sectionbutton so-widget-qzr-sectionbutton-base\"\n\t\t\t\n\t\t><div class=\"sectionbutton-wrapper-small columns-10 center colPadding\">\n\t\t\t\t\t<div class=\"column-of-2 left colPadding sectionbutton-item-small\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/valori\/\">I nostri valori<\/a><\/h3>\n\t\t\t\t\t<div class=\"smalldivider\"><\/div>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/valori\/\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"column-of-2 left colPadding sectionbutton-item-small\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/02\/MRS-25-brochure-29-01-2025.pdf\">Scarica la brochure<\/a><\/h3>\n\t\t\t\t\t<div class=\"smalldivider\"><\/div>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/02\/MRS-25-brochure-29-01-2025.pdf\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><div id=\"panel-19-1-0-2\" class=\"so-panel widget widget_qzr-maincontent\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-19-1-0-2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><div id=\"panel-19-1-0-3\" class=\"so-panel widget widget_qzr-sectionbutton\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-sectionbutton so-widget-qzr-sectionbutton-base\"\n\t\t\t\n\t\t><div class=\"sectionbutton-wrapper-small columns-10 center colPadding\">\n\t\t\t\t\t<div class=\"column-of-2 left colPadding sectionbutton-item-small\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/prodotti\/\">Dispositivi EUROPEI<\/a><\/h3>\n\t\t\t\t\t<div class=\"smalldivider\"><\/div>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/prodotti\/\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"column-of-2 left colPadding sectionbutton-item-small\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/prodotti-mash\/\">Dispositivi MASH<\/a><\/h3>\n\t\t\t\t\t<div class=\"smalldivider\"><\/div>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/prodotti-mash\/\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"column-of-2 left colPadding sectionbutton-item-small\" style=\"background-color:rgba(123,137,142,0.8)\" >\n\t\t\t\t\t<h3><a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/altri-prodotti\/\">Altri Prodotti<\/a><\/h3>\n\t\t\t\t\t<div class=\"smalldivider\"><\/div>\n\t\t\t\t\t<p><\/p>\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/margaritelli-rs.com\/it\/altri-prodotti\/\"><div class=\"icon-arrow-right\"><\/div><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><\/div><\/div><div id=\"panel-19-1-0-4\" class=\"so-panel widget widget_qzr-maincontent panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-2\"  class=\"panel-grid panel-has-style\" ><div class=\"ik pageSection fullscreen panel-row-style panel-row-style-for-19-2\" id=\"milestone\" ><div id=\"pgc-19-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-2-0-0\" class=\"so-panel widget widget_qzr-timeline panel-first-child panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-timeline so-widget-qzr-timeline-base\"\n\t\t\t\n\t\t><div id=\"qzr-timeline-container\" class=\"qzr-timeline\">\n\t<ul class=\"timeline-bkg-holder\">\n\t<li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/1996-3.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/1998-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2001-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2004-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2007-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2009-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2017-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2018-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2019-2.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2022-1.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2025\/05\/2024-1.jpg')\"><\/li>\t<\/ul>\n\t<div class=\"columns-10 center\">\n\t\t<div class=\"timeline-arrow-left\"><span class=\"icon-arrow-left\"><\/span><\/div>\n\t\t<div class=\"timeline-arrow-right\"><span class=\"icon-arrow-right\"><\/span><\/div>\n\t<\/div>\n\t\t\t<h2 style=\"color:\">Milestone<\/h2>\n\t\t\t<ul class=\"timeline-texts-holder columns-8 center colPadding oneColSpacer \">\n\t<li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">1996<\/div><div class=\"timeline-text-title\">Sviluppo dei primi prodotti Margaritelli Road Safety<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">1998<\/div><div class=\"timeline-text-title\">Inizia la collaborazione con il Professor Vittorio Giavotto\u00a0per lo sviluppo di barriere in grado di superare i crash test previsti dalla norma europea<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2001<\/div><div class=\"timeline-text-title\">Prima azienda europea a certificare un barriera in legno ed acciaio per la classe H2 bordo laterale <\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2004<\/div><div class=\"timeline-text-title\">Prima azienda europea a certificare un barriera in legno ed acciaio per la classe H2 bordo ponte<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2007<\/div><div class=\"timeline-text-title\">Certificazione della catena di custodia per lo schema di gestione forestale PEFC ed uso esclusivo di legno certificato secondo tale schema<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2009<\/div><div class=\"timeline-text-title\">Prima azienda in Italia ad ottenere l'emissione dei Certificati di Conformit\u00e0 CE<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2017<\/div><div class=\"timeline-text-title\">Prima azienda europea a certificare una barriera in legno ed acciaio per la classe N2 bordo ponte <\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2018<\/div><div class=\"timeline-text-title\">Validazione dei modelli ad elementi finiti delle barriere &amp; virtual testing in collaborazione con CrashTech<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2019<\/div><div class=\"timeline-text-title\">Prima azienda a certificare un terminale ad assorbimento di energia in legno ed acciaio per la classe di prestazione P1<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2022<\/div><div class=\"timeline-text-title\">Prima azienda italiana a corredare di dispositivi di sicurezza per motociclisti le proprie barriere, in conformit\u00e0 a quanto previsto dal decreto 1 aprile 2019<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2024<\/div><div class=\"timeline-text-title\">Prima barriera di sicurezza stradale \"estetica\" ad essere stata testata con successo in conformit\u00e0 ai requisiti dello standard MASH per il livello TL-3<\/div><div class=\"timeline-text-content\"><\/div><\/li>\t<\/ul>\n\t<ul class=\"timeline-years-holder columns-10 center colPadding\">\n\t<li class=\"timeline-year\">1996<\/li><li class=\"timeline-year\">1998<\/li><li class=\"timeline-year\">2001<\/li><li class=\"timeline-year\">2004<\/li><li class=\"timeline-year\">2007<\/li><li class=\"timeline-year\">2009<\/li><li class=\"timeline-year\">2017<\/li><li class=\"timeline-year\">2018<\/li><li class=\"timeline-year\">2019<\/li><li class=\"timeline-year\">2022<\/li><li class=\"timeline-year\">2024<\/li>\t<\/ul>\n\t<br><br>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-3\"  class=\"panel-grid panel-has-style\" ><div class=\"ik panel-row-style panel-row-style-for-19-3\" ><div id=\"pgc-19-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-3-0-0\" class=\"so-panel widget widget_qzr-maincontent panel-first-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\t\t\t<h2 style=\"color:#7b898e\">Materie prime<\/h2>\n\t\t\n\t\t\t\t\t<div class=\"decoration\" style=\"background-color: #7b898e\"><\/div>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center dontShowOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: left;\"><img class=\"wp-image-18396 alignleft\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2026\/05\/IMG_1516_2.jpg\" alt=\"\" width=\"392\" height=\"395\" \/> <strong>Legno lamellare di abete<\/strong><\/p>\n<p>Utilizziamo solo legno lamellare marcato CE per usi strutturali secondo EN 14080. L\u2019omogeneit\u00e0, la ripetibilit\u00e0 e la costanza delle prestazioni meccaniche sono elementi di rilevante importanza nella costruzione di una barriera stradale di sicurezza affidabile.<\/p>\n<\/div>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: left;\"><img class=\"wp-image-18396 alignleft\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2026\/05\/IMG_1516_2.jpg\" alt=\"\" width=\"392\" height=\"395\" \/> <strong>Legno lamellare di abete<\/strong><\/p>\n<p>Utilizziamo solo legno lamellare marcato CE per usi strutturali secondo EN 14080. L\u2019omogeneit\u00e0, la ripetibilit\u00e0 e la costanza delle prestazioni meccaniche sono elementi di rilevante importanza nella costruzione di una barriera stradale di sicurezza affidabile.<\/p>\n<\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><div id=\"panel-19-3-0-1\" class=\"so-panel widget widget_qzr-maincontent panel-last-child\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\t\t\t<div class=\"decoration\" style=\"background-color: #7b898e\"><\/div>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center dontShowOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: left;\"><img class=\"alignnone wp-image-18398 alignleft\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2026\/05\/IMG_1511_2.jpg\" alt=\"\" width=\"394\" height=\"395\" \/><strong>Acciaio a resistenza migliorata alla corrosione atmosferica<\/strong><\/p>\n<p>Usiamo solo acciaio di tipo S355J0WP secondo EN 10025, marcato CE per usi strutturali - comunemente detto acciaio corten - che permette di coniugare un\u2019eccezionale durata a una spiccata connotazione estetica, creando un ideale connubio cromatico tra il legno e il colore dell\u2019acciaio ossidato.<\/p>\n<\/div>\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><p style=\"text-align: left;\"><img class=\"alignnone wp-image-18398 alignleft\" src=\"https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2026\/05\/IMG_1511_2.jpg\" alt=\"\" width=\"394\" height=\"395\" \/><strong>Acciaio a resistenza migliorata alla corrosione atmosferica<\/strong><\/p>\n<p>Usiamo solo acciaio di tipo S355J0WP secondo EN 10025, marcato CE per usi strutturali - comunemente detto acciaio corten - che permette di coniugare un\u2019eccezionale durata a una spiccata connotazione estetica, creando un ideale connubio cromatico tra il legno e il colore dell\u2019acciaio ossidato.<\/p>\n<\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-4\"  class=\"panel-grid panel-has-style\" ><div class=\"ik pageSection panel-row-style panel-row-style-for-19-4\" id=\"ciclo_produttivo\" ><div id=\"pgc-19-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-4-0-0\" class=\"so-panel widget widget_qzr-timeline panel-first-child panel-last-child\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-timeline so-widget-qzr-timeline-base\"\n\t\t\t\n\t\t><div id=\"qzr-timeline-container\" class=\"qzr-timeline\">\n\t<ul class=\"timeline-bkg-holder\">\n\t<li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/06\/margaritelli_esterni_eterni_full_screen_cnc1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2018\/03\/margaritelli_esterni_eterni_full_screen_cnc_guscio1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/06\/margaritelli_esterni_eterni_full_screen_autoclave1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2018\/03\/margaritelli_esterni_eterni_full_screen_esiccazione_1_1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/06\/margaritelli_esterni_eterni_full_screen_verniciatura1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/06\/margaritelli_esterni_eterni_full_screen_paraffinattura1920x1080.jpg')\"><\/li><li style=\"background-image: url('https:\/\/margaritelli-rs.com\/wp-content\/uploads\/2016\/06\/margaritelli_esterni_eterni_full_screen_pressemblaggio1920x1080.jpg')\"><\/li>\t<\/ul>\n\t<div class=\"columns-10 center\">\n\t\t<div class=\"timeline-arrow-left\"><span class=\"icon-arrow-left\"><\/span><\/div>\n\t\t<div class=\"timeline-arrow-right\"><span class=\"icon-arrow-right\"><\/span><\/div>\n\t<\/div>\n\t\t\t<h2 style=\"color:\">Ciclo produttivo<\/h2>\n\t\t\t<ul class=\"timeline-texts-holder columns-8 center colPadding oneColSpacer \">\n\t<li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">1.1<\/div><div class=\"timeline-text-title\">Lavorazioni meccaniche per fasce di protezione<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">1.2<\/div><div class=\"timeline-text-title\">Lavorazioni a controllo numerico per gusci di rivestimento<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">2<\/div><div class=\"timeline-text-title\">Impregnazione in autoclave con ciclo vuoto - pressione - vuoto<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">3<\/div><div class=\"timeline-text-title\">Ciclo di stagionatura \/ essiccazione<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">4<\/div><div class=\"timeline-text-title\">Impregnazione superficiale idrorepellente<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">5<\/div><div class=\"timeline-text-title\">Paraffinatura delle fibre di testa<\/div><div class=\"timeline-text-content\"><\/div><\/li><li class=\"timeline-text\"><div class=\"timeline-text-year showOnMobile showOnIPadPortrait\">6<\/div><div class=\"timeline-text-title\">Preassemblaggio delle travi lamellari su nastri in acciaio<\/div><div class=\"timeline-text-content\"><\/div><\/li>\t<\/ul>\n\t<ul class=\"timeline-years-holder columns-10 center colPadding\">\n\t<li class=\"timeline-year\">1.1<\/li><li class=\"timeline-year\">1.2<\/li><li class=\"timeline-year\">2<\/li><li class=\"timeline-year\">3<\/li><li class=\"timeline-year\">4<\/li><li class=\"timeline-year\">5<\/li><li class=\"timeline-year\">6<\/li>\t<\/ul>\n\t<br><br>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-5\"  class=\"panel-grid panel-has-style\" ><div class=\"ik pageSection panel-row-style panel-row-style-for-19-5\" id=\"certifications\" ><div id=\"pgc-19-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-5-0-0\" class=\"so-panel widget widget_qzr-vimeo panel-first-child\" data-index=\"11\" ><div class=\"panel-widget-style panel-widget-style-for-19-5-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-vimeo so-widget-qzr-vimeo-base\"\n\t\t\t\n\t\t><div class=\"columns-10 center colPadding\"><div id=\"qzr-vimeo-container\" class=\"qzr-vimeo\" data-url=\"https:\/\/vimeo.com\/260560409\"><\/div><\/div><\/div><\/div><\/div><div id=\"panel-19-5-0-1\" class=\"so-panel widget widget_qzr-maincontent panel-last-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-6\"  class=\"panel-grid panel-has-style\" ><div class=\"ik panel-row-style panel-row-style-for-19-6\" ><div id=\"pgc-19-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-6-0-0\" class=\"so-panel widget widget_qzr-maincontent panel-first-child panel-last-child\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-19-7\"  class=\"panel-grid panel-has-style\" ><div class=\"ik panel-row-style panel-row-style-for-19-7\" ><div id=\"pgc-19-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19-7-0-0\" class=\"so-panel widget widget_qzr-maincontent panel-first-child\" data-index=\"14\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\t\t\t<h2 style=\"color:#ffffff\">Rebranding<\/h2>\n\t\t\n\t\t\n\t\t\t\t\t<h3 class=\"maincontent-subtitle\" style=\"color:#ffffff\">Punto di partenza la storica linea Esterni Eterni, nel segno dell'innovazione e della continuit\u00e0 con i valori aziendali<\/h3>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><div id=\"panel-19-7-0-1\" class=\"so-panel widget widget_qzr-vimeo\" data-index=\"15\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-vimeo so-widget-qzr-vimeo-base\"\n\t\t\t\n\t\t><div class=\"columns-10 center colPadding\"><div id=\"qzr-vimeo-container\" class=\"qzr-vimeo\" data-url=\"https:\/\/vimeo.com\/736472204\"><\/div><\/div><\/div><\/div><div id=\"panel-19-7-0-2\" class=\"so-panel widget widget_qzr-maincontent panel-last-child\" data-index=\"16\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-qzr-maincontent so-widget-qzr-maincontent-base\"\n\t\t\t\n\t\t><div id=\"qzr-maincontent-container\" class=\"qzr-maincontent\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"columns-10 center showOnMobile colPadding maincontent-text\" style=\"color:\"><\/div>\n\t\t\n\t\t<div class=\"columns-10 center colPadding maincontent-profiles\">\n\t\t\t\n\t\t\t\t\t\t<br class=\"clear\">\n\t\t<\/div>\n\t\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Margaritelli Ferroviaria SpA OLTRE 150 ANNI DI PASSIONE PER L&#8217;INNOVAZIONE Fin dalle origini, Margaritelli ha legato il proprio nome al legno e alle ferrovie, contribuendo alla ricostruzione del Paese nel secondo dopoguerra e all&#8217;apertura di\u00a0nuove vie di comunicazione. La ferrovia che sempre simboleggia progresso e civilt\u00e0 e rappresenta la modalit\u00e0 di trasporto pi\u00f9 sicura e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":44,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/pages\/19"}],"collection":[{"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":70,"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":18418,"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/pages\/19\/revisions\/18418"}],"wp:attachment":[{"href":"https:\/\/margaritelli-rs.com\/it\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}